{"id":1923,"date":"2022-10-15T14:41:13","date_gmt":"2022-10-15T14:41:13","guid":{"rendered":"https:\/\/praguehints.com\/?p=1923"},"modified":"2024-05-27T06:42:15","modified_gmt":"2024-05-27T06:42:15","slug":"prague-jewish-city-the-best-preserved-complex-of-jewish-monuments-in-europe","status":"publish","type":"post","link":"https:\/\/praguehints.com\/de\/prague-jewish-city-the-best-preserved-complex-of-jewish-monuments-in-europe\/","title":{"rendered":"J\u00fcdische Stadt Prag \u2013 der am besten erhaltene Komplex j\u00fcdischer Denkm\u00e4ler in Europa"},"content":{"rendered":"<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2182\" src=\"http:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-1024x637.jpg\" width=\"640\" height=\"398\" srcset=\"https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-1024x637.jpg 1024w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-scaled-600x374.jpg 600w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-300x187.jpg 300w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-768x478.jpg 768w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-1536x956.jpg 1536w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-675x420.jpg 675w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-640x398.jpg 640w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-681x424.jpg 681w, https:\/\/praguehints.com\/wp-content\/uploads\/2022\/10\/old-jewish-cemetery-scaled.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Der Gemeindebezirk Josefov ist das kleinste Katastralgebiet Prags, das den Altst\u00e4dter Ring umgibt. Bis 1850 hie\u00df Josefov \u201e<strong>J\u00fcdische Stadt<\/strong>&#039;, schon fr\u00fcher wurde dieser Teil das j\u00fcdische Ghetto genannt. Heute ist es ein gut erhaltener Komplex wichtiger j\u00fcdischer Denkm\u00e4ler von europ\u00e4ischer Bedeutung.<\/p>\n<p>Das urspr\u00fcngliche j\u00fcdische Ghetto wurde Ende der 80er Jahre des 19. Jahrhunderts als Slum zur \u201eSanit\u00e4rversorgung\u201c verurteilt. Aus dem Ghetto sind nur wenige Geb\u00e4ude erhalten geblieben, darunter das J\u00fcdische Rathaus, der Alte J\u00fcdische Friedhof und sechs Synagogen: Klausov\u00e1, Maiselova, Pinkasova, Staronov\u00e1, Spaniel\u00e1 und Vysok\u00e1-Synagoge.<\/p>\n<p>Im Zweiten Weltkrieg wurden Juden in Konzentrationslager deportiert. Die verlassene Josefstadt wurde zum Lagerhaus f\u00fcr beschlagnahmtes Eigentum. Nach Kriegsende blieben viele der Reliquien im Besitz des J\u00fcdischen Museums, da ihre urspr\u00fcnglichen Besitzer in Konzentrationslagern ermordet wurden<\/p>\n<hr \/>\n<p>So wurde es zum zweitgr\u00f6\u00dften j\u00fcdischen Museum der Welt. Obwohl nur einige der wichtigsten Denkm\u00e4ler der jahrhundertealten Geschichte der Prager Juden erhalten werden konnten, bilden sie doch die am besten erhaltene Gesamtheit j\u00fcdischer Denkm\u00e4ler in Europa.<\/p>\n<p>Das J\u00fcdische Museum bietet Besuchern eine F\u00fchrung mit ausschlie\u00dflich tschechischer Fachdolmetschung zu einem erheblichen Preisnachlass an. Diese Tour findet an Sonn- und Feiertagen um 14:00 Uhr statt. Erwachsene zahlen 95 CZK, Kinder unter 6 Jahren haben freien Eintritt und Kinder von 6 bis 15 Jahren, Studenten und Rentner zahlen 55 CZK.<\/p>\n<p>Das Antisemitismus-Aufkl\u00e4rungsprogramm in der Tschechischen Republik umfasst auch einen gef\u00fchrten Eintritt in das J\u00fcdische Museum und die Alte Synagoge. Tickets m\u00fcssen in der Reservierungszentrale des J\u00fcdischen Museums in der Klaus-Synagoge erworben werden. F\u00fcr einen Erwachsenen kostet es 130 CZK, Kinder unter 6 Jahren haben freien Eintritt und Kinder von 6 bis 15 Jahren, Studenten und Rentner zahlen 80 CZK.<\/p>\n<h2 class=\"promoter\"><strong>Operator<\/strong><\/h2>\n<ul>\n<li>J\u00fcdische Gemeinde in Prag<br \/>\nMaiselova 18 110 01 Prag 1<\/li>\n<li><strong>Tel<\/strong>.:+420 224 800 812<\/li>\n<li><strong>Email<\/strong>:secretariat@kehil\u2026<\/li>\n<li><strong>WWW<\/strong>:www.kehilaprag.cz<\/li>\n<li><strong>GPS<\/strong>:50.089096 14.418000<\/li>\n<\/ul>\n<ul>\n<li><strong>Region<\/strong>:Prag<\/li>\n<li><strong>Stadt<\/strong>:Prag 1<\/li>\n<\/ul>\n<h2 class=\"time\"><strong>Dauer<\/strong><\/h2>\n<p><strong>1-3 Stunden<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>The municipal district of Josefov is the smallest cadastral territory of Prague that surrounds the Old Town Square. Until 1850, Josefov was called the \u2018Jewish Town\u2019, even earlier this part was called the Jewish Ghetto. Today it is a well-preserved complex of important Jewish monuments of European significance. The original Jewish ghetto was in the [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[170],"tags":[],"class_list":["post-1923","post","type-post","status-publish","format-standard","hentry","category-jewish-monuments-around-prague"],"_links":{"self":[{"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/posts\/1923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/comments?post=1923"}],"version-history":[{"count":0,"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/posts\/1923\/revisions"}],"wp:attachment":[{"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/media?parent=1923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/categories?post=1923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/praguehints.com\/de\/wp-json\/wp\/v2\/tags?post=1923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}